{"id":2326,"date":"2020-01-28T15:21:25","date_gmt":"2020-01-28T15:21:25","guid":{"rendered":"https:\/\/roboticslab.uc3m.es\/doctoral_thesis\/ayuda-personas-mayores-con-un-robot-social-estimulacion-cognitiva\/"},"modified":"2024-02-27T18:57:47","modified_gmt":"2024-02-27T18:57:47","slug":"ayuda-personas-mayores-con-un-robot-social-estimulacion-cognitiva","status":"publish","type":"doctoral_thesis","link":"https:\/\/roboticslab.uc3m.es\/es\/doctoral_thesis\/ayuda-personas-mayores-con-un-robot-social-estimulacion-cognitiva\/","title":{"rendered":"Ayuda a personas mayores con un robot social: Estimulaci\u00f3n cognitiva"},"content":{"rendered":"<p align=\"justify\">Los pa\u00edses desarrollados se enfrentan a un envejecimiento progresivo de la poblaci\u00f3n, debido al descenso de la tasa de natalidad y al aumento de la esperanza de vida. En estas sociedades, asegurar el bienestar de un porcentaje muy elevado de personas mayores plantea grandes problemas econ\u00f3micos y sociales.  Adem\u00e1s, gran parte de estos mayores desean alargar en la medida de lo posible su vida independiente, residiendo en sus propios domicilios. Para hacer frente a este reto, las ayudas tecnol\u00f3gicas pueden ser de gran ayuda, y entre estas se encuentran los robots sociales. Teniendo en cuenta esto, los dos objetivos principales de esta tesis fueron: definir las caracter\u00edsticas y funcionalidades de un robot social para ayudar a mayores con un deterioro cognitivo leve en sus propios domicilios, y desarrollar un programa terap\u00e9utico de estimulaci\u00f3n cognitiva con el robot. <\/p>\n<p align=\"justify\">De cara al desarrollo de esta terapia, se hizo necesario un an\u00e1lisis de los principales m\u00e9todos ya existentes, y de las ventajas y desventajas que pod\u00eda suponer el uso de un robot para ese fin. La estimulaci\u00f3n cognitiva con robots es una t\u00e9cnica muy novedosa, que presenta algunas ventajas importantes respecto a las t\u00e9cnicas empleadas en la actualidad. En particular, destaca el hecho de poder llevar a cabo la estimulaci\u00f3n en el propio domicilio de la persona mayor y poder distribuirse en el tiempo, intercal\u00e1ndola con otras actividades, como pueden ser actividades de entretenimiento. Esto contrasta con las t\u00e9cnicas tradicionales, en las que se suele concentrar la estimulaci\u00f3n en unos pocas sesiones cada semana realizadas fuera del domicilio del mayor. <\/p>\n<p align=\"justify\">Dado que cada persona mayor tiene gustos y capacidades diferentes, los desarrollos llevados a cabo en el robot se han hecho de forma que permitan un alto grado de adaptaci\u00f3n a las particularidades de cada usuario. Esta adaptaci\u00f3n la realiza de forma remota personal especializado en asistencia geri\u00e1trica. Para facilitar esta labor, el robot almacena informaci\u00f3n relevante de las actividades que la persona mayor realiza con \u00e9l, en particular las relacionadas con la estimulaci\u00f3n cognitiva, a fin de que los terapeutas puedan monitorizar la evoluci\u00f3n del usuario y ajustar en base a ellas el comportamiento del robot. <\/p>\n<p align=\"justify\">El que la estimulaci\u00f3n cognitiva pueda realizarse de forma distribuida, y no concentrada en unas pocas sesiones como se hace tradicionalmente, ha hecho necesario definir un m\u00e9todo novedoso para pautar la terapia. Los resultados de esta tesis han sido evaluados por personal especializado en asistencia a personas mayores, y han sido probados con personas mayores en diversos centros geri\u00e1tricos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los pa\u00edses desarrollados se enfrentan a un envejecimiento progresivo de la poblaci\u00f3n, debido al descenso de la tasa de natalidad y al aumento de la esperanza de vida. En estas sociedades, asegurar el bienestar de un porcentaje muy elevado de personas mayores plantea grandes problemas econ\u00f3micos y sociales. Adem\u00e1s, gran parte de estos mayores desean [&hellip;]<\/p>\n","protected":false},"author":57,"featured_media":0,"template":"","meta":{"_acf_changed":false},"categories":[58],"class_list":["post-2326","doctoral_thesis","type-doctoral_thesis","status-publish","hentry","category-doctoral-thesis"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ayuda a personas mayores con un robot social: Estimulaci\u00f3n cognitiva - Laboratorio de rob\u00f3tica<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ayuda a personas mayores con un robot social: Estimulaci\u00f3n cognitiva - Laboratorio de rob\u00f3tica\" \/>\n<meta property=\"og:description\" content=\"Los pa\u00edses desarrollados se enfrentan a un envejecimiento progresivo de la poblaci\u00f3n, debido al descenso de la tasa de natalidad y al aumento de la esperanza de vida. En estas sociedades, asegurar el bienestar de un porcentaje muy elevado de personas mayores plantea grandes problemas econ\u00f3micos y sociales. Adem\u00e1s, gran parte de estos mayores desean [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/roboticslab.uc3m.es\/doctoral_thesis\/ayuda-personas-mayores-con-un-robot-social-estimulacion-cognitiva\/\" \/>\n<meta property=\"og:site_name\" content=\"Laboratorio de rob\u00f3tica\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-27T18:57:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/roboticslab.uc3m.es\/doctoral_thesis\/ayuda-personas-mayores-con-un-robot-social-estimulacion-cognitiva\/\",\"url\":\"https:\/\/roboticslab.uc3m.es\/doctoral_thesis\/ayuda-personas-mayores-con-un-robot-social-estimulacion-cognitiva\/\",\"name\":\"Ayuda a personas mayores con un robot social: Estimulaci\u00f3n cognitiva - Laboratorio de rob\u00f3tica\",\"isPartOf\":{\"@id\":\"https:\/\/roboticslab.uc3m.es\/#website\"},\"datePublished\":\"2020-01-28T15:21:25+00:00\",\"dateModified\":\"2024-02-27T18:57:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/roboticslab.uc3m.es\/doctoral_thesis\/ayuda-personas-mayores-con-un-robot-social-estimulacion-cognitiva\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/roboticslab.uc3m.es\/doctoral_thesis\/ayuda-personas-mayores-con-un-robot-social-estimulacion-cognitiva\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/roboticslab.uc3m.es\/doctoral_thesis\/ayuda-personas-mayores-con-un-robot-social-estimulacion-cognitiva\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Doctoral Thesis\",\"item\":\"https:\/\/roboticslab.uc3m.es\/category\/doctoral-thesis\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ayuda a personas mayores con un robot social: Estimulaci\u00f3n cognitiva\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/roboticslab.uc3m.es\/#website\",\"url\":\"https:\/\/roboticslab.uc3m.es\/\",\"name\":\"Laboratorio de rob\u00f3tica\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/roboticslab.uc3m.es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/roboticslab.uc3m.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/roboticslab.uc3m.es\/#organization\",\"name\":\"Laboratorio de rob\u00f3tica\",\"url\":\"https:\/\/roboticslab.uc3m.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/roboticslab.uc3m.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/roboticslab.uc3m.es\/wp-content\/uploads\/2024\/02\/cropped-logo_header_roboticslab_0_new-1.png\",\"contentUrl\":\"https:\/\/roboticslab.uc3m.es\/wp-content\/uploads\/2024\/02\/cropped-logo_header_roboticslab_0_new-1.png\",\"width\":304,\"height\":68,\"caption\":\"Laboratorio de rob\u00f3tica\"},\"image\":{\"@id\":\"https:\/\/roboticslab.uc3m.es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ayuda a personas mayores con un robot social: Estimulaci\u00f3n cognitiva - Laboratorio de rob\u00f3tica","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Ayuda a personas mayores con un robot social: Estimulaci\u00f3n cognitiva - Laboratorio de rob\u00f3tica","og_description":"Los pa\u00edses desarrollados se enfrentan a un envejecimiento progresivo de la poblaci\u00f3n, debido al descenso de la tasa de natalidad y al aumento de la esperanza de vida. En estas sociedades, asegurar el bienestar de un porcentaje muy elevado de personas mayores plantea grandes problemas econ\u00f3micos y sociales. Adem\u00e1s, gran parte de estos mayores desean [&hellip;]","og_url":"https:\/\/roboticslab.uc3m.es\/doctoral_thesis\/ayuda-personas-mayores-con-un-robot-social-estimulacion-cognitiva\/","og_site_name":"Laboratorio de rob\u00f3tica","article_modified_time":"2024-02-27T18:57:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/roboticslab.uc3m.es\/doctoral_thesis\/ayuda-personas-mayores-con-un-robot-social-estimulacion-cognitiva\/","url":"https:\/\/roboticslab.uc3m.es\/doctoral_thesis\/ayuda-personas-mayores-con-un-robot-social-estimulacion-cognitiva\/","name":"Ayuda a personas mayores con un robot social: Estimulaci\u00f3n cognitiva - Laboratorio de rob\u00f3tica","isPartOf":{"@id":"https:\/\/roboticslab.uc3m.es\/#website"},"datePublished":"2020-01-28T15:21:25+00:00","dateModified":"2024-02-27T18:57:47+00:00","breadcrumb":{"@id":"https:\/\/roboticslab.uc3m.es\/doctoral_thesis\/ayuda-personas-mayores-con-un-robot-social-estimulacion-cognitiva\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/roboticslab.uc3m.es\/doctoral_thesis\/ayuda-personas-mayores-con-un-robot-social-estimulacion-cognitiva\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/roboticslab.uc3m.es\/doctoral_thesis\/ayuda-personas-mayores-con-un-robot-social-estimulacion-cognitiva\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Doctoral Thesis","item":"https:\/\/roboticslab.uc3m.es\/category\/doctoral-thesis\/"},{"@type":"ListItem","position":2,"name":"Ayuda a personas mayores con un robot social: Estimulaci\u00f3n cognitiva"}]},{"@type":"WebSite","@id":"https:\/\/roboticslab.uc3m.es\/#website","url":"https:\/\/roboticslab.uc3m.es\/","name":"Laboratorio de rob\u00f3tica","description":"","publisher":{"@id":"https:\/\/roboticslab.uc3m.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/roboticslab.uc3m.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/roboticslab.uc3m.es\/#organization","name":"Laboratorio de rob\u00f3tica","url":"https:\/\/roboticslab.uc3m.es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/roboticslab.uc3m.es\/#\/schema\/logo\/image\/","url":"https:\/\/roboticslab.uc3m.es\/wp-content\/uploads\/2024\/02\/cropped-logo_header_roboticslab_0_new-1.png","contentUrl":"https:\/\/roboticslab.uc3m.es\/wp-content\/uploads\/2024\/02\/cropped-logo_header_roboticslab_0_new-1.png","width":304,"height":68,"caption":"Laboratorio de rob\u00f3tica"},"image":{"@id":"https:\/\/roboticslab.uc3m.es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/roboticslab.uc3m.es\/es\/wp-json\/wp\/v2\/doctoral_thesis\/2326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roboticslab.uc3m.es\/es\/wp-json\/wp\/v2\/doctoral_thesis"}],"about":[{"href":"https:\/\/roboticslab.uc3m.es\/es\/wp-json\/wp\/v2\/types\/doctoral_thesis"}],"author":[{"embeddable":true,"href":"https:\/\/roboticslab.uc3m.es\/es\/wp-json\/wp\/v2\/users\/57"}],"wp:attachment":[{"href":"https:\/\/roboticslab.uc3m.es\/es\/wp-json\/wp\/v2\/media?parent=2326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roboticslab.uc3m.es\/es\/wp-json\/wp\/v2\/categories?post=2326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}